{"id":152,"count":1,"description":"","link":"https:\/\/casasupertubos.com\/en\/acf-localizacoes\/portugal\/","name":"Portugal","slug":"portugal","taxonomy":"acf-localizacoes","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/casasupertubos.com\/en\/wp-json\/wp\/v2\/acf-localizacoes\/152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casasupertubos.com\/en\/wp-json\/wp\/v2\/acf-localizacoes"}],"about":[{"href":"https:\/\/casasupertubos.com\/en\/wp-json\/wp\/v2\/taxonomies\/acf-localizacoes"}],"wp:post_type":[{"href":"https:\/\/casasupertubos.com\/en\/wp-json\/wp\/v2\/dica-de-viagem?acf-localizacoes=152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}