{"id":114,"count":3,"description":"","link":"https:\/\/casasupertubos.com\/en\/category\/surf\/","name":"Surf","slug":"surf","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/casasupertubos.com\/en\/wp-json\/wp\/v2\/categories\/114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casasupertubos.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/casasupertubos.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/casasupertubos.com\/en\/wp-json\/wp\/v2\/posts?categories=114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}